{"id":1332,"date":"2022-07-17T13:21:51","date_gmt":"2022-07-17T17:21:51","guid":{"rendered":"https:\/\/sogemec.impulsionmedia.com\/employe\/jessica-smedo\/"},"modified":"2024-06-20T00:20:38","modified_gmt":"2024-06-20T04:20:38","slug":"jessica-smedo","status":"publish","type":"employe","link":"https:\/\/sogemec.com\/en\/employe\/jessica-smedo\/","title":{"rendered":"Jessica Smedo"},"featured_media":3060,"template":"","poste":[54],"profil":[14,13],"class_list":["post-1332","employe","type-employe","status-publish","has-post-thumbnail","hentry","poste-advisor","profil-etudiant-en-medecine","profil-medecin-resident"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Jessica Smedo - Sogemec Assurances<\/title>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Jessica Smedo - Sogemec Assurances\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sogemec.com\/en\/employe\/jessica-smedo\/\" \/>\n<meta property=\"og:site_name\" content=\"Sogemec Assurances\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/fr-ca.facebook.com\/sogemec.assurances\/\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-20T04:20:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sogemec.com\/wp-content\/uploads\/Jessica-Smedo-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sogemec.com\\\/en\\\/employe\\\/jessica-smedo\\\/\",\"url\":\"https:\\\/\\\/sogemec.com\\\/en\\\/employe\\\/jessica-smedo\\\/\",\"name\":\"Jessica Smedo - Sogemec Assurances\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sogemec.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/sogemec.com\\\/en\\\/employe\\\/jessica-smedo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/sogemec.com\\\/en\\\/employe\\\/jessica-smedo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sogemec.com\\\/wp-content\\\/uploads\\\/Jessica-Smedo-1.jpg\",\"datePublished\":\"2022-07-17T17:21:51+00:00\",\"dateModified\":\"2024-06-20T04:20:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sogemec.com\\\/en\\\/employe\\\/jessica-smedo\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sogemec.com\\\/en\\\/employe\\\/jessica-smedo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/sogemec.com\\\/en\\\/employe\\\/jessica-smedo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/sogemec.com\\\/wp-content\\\/uploads\\\/Jessica-Smedo-1.jpg\",\"contentUrl\":\"https:\\\/\\\/sogemec.com\\\/wp-content\\\/uploads\\\/Jessica-Smedo-1.jpg\",\"width\":300,\"height\":300,\"caption\":\"Jessica Smedo\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sogemec.com\\\/en\\\/employe\\\/jessica-smedo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/sogemec.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Jessica Smedo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sogemec.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/sogemec.com\\\/en\\\/\",\"name\":\"Sogemec Assurances\",\"description\":\"Cabinet en services financiers pour professionnels depuis 1978\",\"publisher\":{\"@id\":\"https:\\\/\\\/sogemec.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sogemec.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/sogemec.com\\\/en\\\/#organization\",\"name\":\"Sogemec Assurances\",\"url\":\"https:\\\/\\\/sogemec.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/sogemec.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/sogemec.com\\\/wp-content\\\/uploads\\\/Sogemec-Assurances-Logo.png\",\"contentUrl\":\"https:\\\/\\\/sogemec.com\\\/wp-content\\\/uploads\\\/Sogemec-Assurances-Logo.png\",\"width\":300,\"height\":126,\"caption\":\"Sogemec Assurances\"},\"image\":{\"@id\":\"https:\\\/\\\/sogemec.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/fr-ca.facebook.com\\\/sogemec.assurances\\\/\",\"https:\\\/\\\/ca.linkedin.com\\\/company\\\/sogemec-assurances\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Jessica Smedo - Sogemec Assurances","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"en_US","og_type":"article","og_title":"Jessica Smedo - Sogemec Assurances","og_url":"https:\/\/sogemec.com\/en\/employe\/jessica-smedo\/","og_site_name":"Sogemec Assurances","article_publisher":"https:\/\/fr-ca.facebook.com\/sogemec.assurances\/","article_modified_time":"2024-06-20T04:20:38+00:00","og_image":[{"width":300,"height":300,"url":"https:\/\/sogemec.com\/wp-content\/uploads\/Jessica-Smedo-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/sogemec.com\/en\/employe\/jessica-smedo\/","url":"https:\/\/sogemec.com\/en\/employe\/jessica-smedo\/","name":"Jessica Smedo - Sogemec Assurances","isPartOf":{"@id":"https:\/\/sogemec.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sogemec.com\/en\/employe\/jessica-smedo\/#primaryimage"},"image":{"@id":"https:\/\/sogemec.com\/en\/employe\/jessica-smedo\/#primaryimage"},"thumbnailUrl":"https:\/\/sogemec.com\/wp-content\/uploads\/Jessica-Smedo-1.jpg","datePublished":"2022-07-17T17:21:51+00:00","dateModified":"2024-06-20T04:20:38+00:00","breadcrumb":{"@id":"https:\/\/sogemec.com\/en\/employe\/jessica-smedo\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sogemec.com\/en\/employe\/jessica-smedo\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/sogemec.com\/en\/employe\/jessica-smedo\/#primaryimage","url":"https:\/\/sogemec.com\/wp-content\/uploads\/Jessica-Smedo-1.jpg","contentUrl":"https:\/\/sogemec.com\/wp-content\/uploads\/Jessica-Smedo-1.jpg","width":300,"height":300,"caption":"Jessica Smedo"},{"@type":"BreadcrumbList","@id":"https:\/\/sogemec.com\/en\/employe\/jessica-smedo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/sogemec.com\/en\/"},{"@type":"ListItem","position":2,"name":"Jessica Smedo"}]},{"@type":"WebSite","@id":"https:\/\/sogemec.com\/en\/#website","url":"https:\/\/sogemec.com\/en\/","name":"Sogemec Assurances","description":"Cabinet en services financiers pour professionnels depuis 1978","publisher":{"@id":"https:\/\/sogemec.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sogemec.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/sogemec.com\/en\/#organization","name":"Sogemec Assurances","url":"https:\/\/sogemec.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/sogemec.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/sogemec.com\/wp-content\/uploads\/Sogemec-Assurances-Logo.png","contentUrl":"https:\/\/sogemec.com\/wp-content\/uploads\/Sogemec-Assurances-Logo.png","width":300,"height":126,"caption":"Sogemec Assurances"},"image":{"@id":"https:\/\/sogemec.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/fr-ca.facebook.com\/sogemec.assurances\/","https:\/\/ca.linkedin.com\/company\/sogemec-assurances"]}]}},"_links":{"self":[{"href":"https:\/\/sogemec.com\/en\/wp-json\/wp\/v2\/employe\/1332","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sogemec.com\/en\/wp-json\/wp\/v2\/employe"}],"about":[{"href":"https:\/\/sogemec.com\/en\/wp-json\/wp\/v2\/types\/employe"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sogemec.com\/en\/wp-json\/wp\/v2\/media\/3060"}],"wp:attachment":[{"href":"https:\/\/sogemec.com\/en\/wp-json\/wp\/v2\/media?parent=1332"}],"wp:term":[{"taxonomy":"poste","embeddable":true,"href":"https:\/\/sogemec.com\/en\/wp-json\/wp\/v2\/poste?post=1332"},{"taxonomy":"profil","embeddable":true,"href":"https:\/\/sogemec.com\/en\/wp-json\/wp\/v2\/profil?post=1332"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}